{"id":1041,"date":"2019-10-03T11:08:45","date_gmt":"2019-10-03T08:08:45","guid":{"rendered":"https:\/\/web-mng.iptp.com\/?page_id=1041"},"modified":"2025-05-15T06:37:53","modified_gmt":"2025-05-15T03:37:53","slug":"testimonials","status":"publish","type":"page","link":"https:\/\/www.iptp.org\/es_ES\/about-us\/testimonials\/","title":{"rendered":"Testimonios"},"content":{"rendered":"<div class=\"wrap-testimonial\">\n<blockquote><p><img decoding=\"async\" loading=\"lazy\" class=\"lazy alignright img-xs-100 wp-image-1052 size-full\" src=\"data:image\/gif;base64,R0lGODlhAQABAAD\/ACwAAAAAAQABAAACADs=\" alt=\"AMS-IX\" data-src=\"\/wp-content\/uploads\/amsixlogolong.png\" width=\"150\" height=\"80\"><\/p><noscript><img decoding=\"async\" loading=\"lazy\" class=\"alignright img-xs-100 wp-image-1052 size-full lazy\" alt=\"AMS-IX\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" width=\"150\" height=\"80\" data-src=\"\/wp-content\/uploads\/amsixlogolong.png\"><\/noscript>&ldquo;La infraestructura de red de IPTP Networks abarca ubicaciones clave de centros de datos en todos los continentes. Esta fortaleza clave, junto con su enfoque innovador y flexible, los convierte en el partido perfecto para revender el servicio AMS-IX de forma remota.&rdquo;<\/blockquote>\n<p style=\"text-align: right;\">Mark Cooper, CCO en AMS-IX.<\/p>\n<hr>\n<blockquote><p><img decoding=\"async\" loading=\"lazy\" class=\"lazy alignright img-xs-100 wp-image-1052 size-full\" src=\"data:image\/gif;base64,R0lGODlhAQABAAD\/ACwAAAAAAQABAAACADs=\" alt=\"BroadBand Tower, Inc\" data-src=\"\/wp-content\/uploads\/BBT2.png\" width=\"150\" height=\"80\"><\/p><noscript><img decoding=\"async\" loading=\"lazy\" class=\"alignright img-xs-100 wp-image-1052 size-full lazy\" alt=\"BroadBand Tower, Inc\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" width=\"150\" height=\"80\" data-src=\"\/wp-content\/uploads\/BBT2.png\"><\/noscript>&ldquo;IPTP es un socio clave que ayud&oacute; a crear nuestro Centro de datos de Otemachi, donde se re&uacute;nen muchos IX\/ISP japoneses, en un centro con verdadera conectividad global.&rdquo;<\/blockquote>\n<p style=\"text-align: right;\">Yosuke Hiyama, Miembro de la Junta Directiva, Director de Operaciones, DC, Cloud &amp; Storage Sales,en BroadBand Tower, Inc.<\/p>\n<hr>\n<blockquote><p><img decoding=\"async\" loading=\"lazy\" class=\"lazy alignright size-full wp-image-14020\" src=\"data:image\/gif;base64,R0lGODlhAQABAAD\/ACwAAAAAAQABAAACADs=\" data-src=\"\/wp-content\/uploads\/Cataleya-logo.png\" alt=\"Cataleya\" width=\"198\" height=\"80\"><\/p><noscript><img decoding=\"async\" loading=\"lazy\" class=\"alignright size-full wp-image-14020 lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"Cataleya\" width=\"198\" height=\"80\" data-src=\"\/wp-content\/uploads\/Cataleya-logo.png\"><\/noscript>&ldquo;Como empresa de software de plataforma de mensajer&iacute;a y voz, con una gran ambici&oacute;n de convertirnos en un l&iacute;der en soluciones de CPaaS para proveedores de servicios de comunicaci&oacute;n, nuestro socio de infraestructura tiene que entender y ser capaz de soportar plataformas de comunicaciones en tiempo real muy, muy bien. Son sensibles por naturaleza a la latencia y el jitter, y requieren una disponibilidad s&uacute;per alta en general, y creemos que hemos encontrado ese socio en IPTP y su gran soporte y tiempos de respuesta, junto con su alcance global son la guinda del pastel.&rdquo;<\/blockquote>\n<p style=\"text-align: right;\">Andreas Hipp CEO de Cataleya<\/p>\n<hr>\n<blockquote><p><img decoding=\"async\" loading=\"lazy\" class=\"lazy alignright img-xs-100 wp-image-1052 size-full\" src=\"data:image\/gif;base64,R0lGODlhAQABAAD\/ACwAAAAAAQABAAACADs=\" alt=\"CMC Telecom\" data-src=\"\/wp-content\/uploads\/CMC.png\" width=\"150\" height=\"80\"><\/p><noscript><img decoding=\"async\" loading=\"lazy\" class=\"alignright img-xs-100 wp-image-1052 size-full lazy\" alt=\"CMC Telecom\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" width=\"150\" height=\"80\" data-src=\"\/wp-content\/uploads\/CMC.png\"><\/noscript>&ldquo;Estamos encantados de asociarnos con IPTP, ya que ofrece una amplia gama de activos de cable global y conectividad de baja latencia a los principales centros mundiales y regionales. Esta colaboraci&oacute;n confiable nos ha permitido aprovechar su s&oacute;lido footprint de red y servir a nuestros respectivos clientes con experiencias sobresalientes.&rdquo;<\/blockquote>\n<p style=\"text-align: right;\">Mr. Dang Tung Son CMO\/DCEO en CMC Telecom<\/p>\n<hr>\n<blockquote><p><img decoding=\"async\" loading=\"lazy\" class=\"lazy margbottom100 img-xs-100 alignright wp-image-1052 size-full\" src=\"data:image\/gif;base64,R0lGODlhAQABAAD\/ACwAAAAAAQABAAACADs=\" alt=\"Notesco Financial Services Ltd\" data-src=\"\/wp-content\/uploads\/notesco.jpg\" width=\"151\" height=\"81\"><\/p><noscript><img decoding=\"async\" loading=\"lazy\" class=\"margbottom100 img-xs-100 alignright wp-image-1052 size-full lazy\" alt=\"Notesco Financial Services Ltd\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" width=\"151\" height=\"81\" data-src=\"\/wp-content\/uploads\/notesco.jpg\"><\/noscript>&ldquo;Nuestras empresas se desarrollaron en asociaci&oacute;n con IPTP Networks y, de hecho, gran parte de nuestro &eacute;xito se puede atribuir a la elecci&oacute;n de IPTP como proveedor de servicios. Uno de los factores m&aacute;s importantes en los negocios es tener un socio confiable y seguro en quien podamos confiar. Me enorgullece decir que, sin duda, tenemos un socio as&iacute;.&rdquo;<\/blockquote>\n<p style=\"text-align: right;\">Markos A. Kashiouris, Presidente &amp; CEO en Notesco Financial Services Ltd<\/p>\n<hr>\n<blockquote><p><img decoding=\"async\" loading=\"lazy\" class=\"lazy margbottom100 img-xs-100 alignright wp-image-1052 size-full\" src=\"data:image\/gif;base64,R0lGODlhAQABAAD\/ACwAAAAAAQABAAACADs=\" alt=\"eASPNet\" data-src=\"\/wp-content\/uploads\/easpnet-logo.png\" width=\"150\" height=\"55\"><\/p><noscript><img decoding=\"async\" loading=\"lazy\" class=\"margbottom100 img-xs-100 alignright wp-image-1052 size-full lazy\" alt=\"eASPNet\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" width=\"150\" height=\"55\" data-src=\"\/wp-content\/uploads\/easpnet-logo.png\"><\/noscript>&ldquo;Nuestros servicios en la nube, incluida la nube h&iacute;brida GWS y el dispositivo GWStack construidos en la plataforma de nube basada en la tecnolog&iacute;a VMware, pueden conectarse no solo a la plataforma eASPNet, sino tambi&eacute;n a una serie de proveedores de nube internacionales como AWS, Azure, Google, Alibaba Cloud, etc. Esto es posible gracias a nuestra brillante asociaci&oacute;n con IPTP Networks como un proveedor global de conexiones de red de alta velocidad para servicios en la nube premium de cross-cloud y  multi-cloud.&rdquo;<\/blockquote>\n<p style=\"text-align: right;\">Jackson Wu, eASPNet, Presidente<\/p>\n<hr>\n<blockquote>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"lazy size-full img-xs-100 wp-image-1058 alignright\" src=\"data:image\/gif;base64,R0lGODlhAQABAAD\/ACwAAAAAAQABAAACADs=\" alt=\"CardPay Inc\" data-src=\"\/wp-content\/uploads\/cardpayinc.png\" width=\"150\" height=\"80\"><\/p><noscript><img decoding=\"async\" loading=\"lazy\" class=\"size-full img-xs-100 wp-image-1058 alignright lazy\" alt=\"CardPay Inc\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" width=\"150\" height=\"80\" data-src=\"\/wp-content\/uploads\/cardpayinc.png\"><\/noscript>&ldquo;Durante el tiempo que CardPay ha estado trabajando con IPTP, hemos disfrutado de servidores y servidores de hosting estables y seguros, lo que nos permiti&oacute; crecer y lograr un mayor &eacute;xito, gracias a sus soluciones de negocios flexibles y robustas.&rdquo;\n<\/blockquote>\n<p style=\"text-align: right;\">Paul Dalziel, Gerente de Relaciones Comerciales en CardPay Inc.<\/p>\n<p><!--\n\n\n<hr \/>\n\n\n\n\n\n<blockquote>\n\n\n<p><img  decoding=\"async\" loading=\"lazy\"  class=\"lazy size-full img-xs-100 wp-image-1060 alignright\" src=\"data:image\/gif;base64,R0lGODlhAQABAAD\/ACwAAAAAAQABAAACADs=\"   data-src=\"\/wp-content\/uploads\/power-alllogo.png\"  alt=\"\" width=\"150\" height=\"80\" \/><noscript><img decoding=\"async\" loading=\"lazy\" class=\"size-full img-xs-100 wp-image-1060 alignright\" src=\"\/wp-content\/uploads\/power-alllogo.png\" alt=\"\" width=\"150\" height=\"80\" \/><\/noscript>''IPTP Networks nos brind&oacute; una infraestructura de red confiable, robusta, segura y de f&aacute;cil acceso para soportar nuestra plataforma global inter-cloud''<\/p>\n\n\n<\/blockquote>\n\n\n\n\n<p style=\"text-align: right;\">Peter So, Vice-presidente en Power-All Networks Ltd<\/p>\n\n\n\n--><\/p>\n<hr>\n<blockquote>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"lazy size-full img-xs-100 wp-image-1070 alignright\" src=\"data:image\/gif;base64,R0lGODlhAQABAAD\/ACwAAAAAAQABAAACADs=\" alt=\"KPM Consulting\" data-src=\"\/wp-content\/uploads\/blanklogo.png\" width=\"150\" height=\"80\"><\/p><noscript><img decoding=\"async\" loading=\"lazy\" class=\"size-full img-xs-100 wp-image-1070 alignright lazy\" alt=\"KPM Consulting\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" width=\"150\" height=\"80\" data-src=\"\/wp-content\/uploads\/blanklogo.png\"><\/noscript>&rdquo;Gracias a IPTP Networks, unificamos todas nuestras comunicaciones en una sola plataforma basada en IP. Desde entonces, nuestra empresa ha reducido significativamente los costos de comunicaci&oacute;n y al mismo tiempo ha aumentado la productividad de los empleados.&rdquo;\n<\/blockquote>\n<p style=\"text-align: right;\">Chryso Panayi, KPM Consulting, Chipre<\/p>\n<hr>\n<blockquote>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"lazy size-full img-xs-100 wp-image-1070 alignright\" src=\"data:image\/gif;base64,R0lGODlhAQABAAD\/ACwAAAAAAQABAAACADs=\" alt=\"Advection.NET\" data-src=\"\/wp-content\/uploads\/logoadv.png\" width=\"150\" height=\"80\"><\/p><noscript><img decoding=\"async\" loading=\"lazy\" class=\"size-full img-xs-100 wp-image-1070 alignright lazy\" alt=\"Advection.NET\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" width=\"150\" height=\"80\" data-src=\"\/wp-content\/uploads\/logoadv.png\"><\/noscript>&rdquo;IPTP ha sido un socio de infraestructura confiable para nuestro global video CDN. Debido a que ofrecemos servicios de transmisi&oacute;n en vivo de baja latencia a las principales marcas, a menudo necesitamos escalar para administrar la afluencia de nuevos espectadores, y siempre podemos contar con IPTP para obtener capacidad adicional.&rdquo;\n<\/blockquote>\n<p style=\"text-align: right;\">Vlad Ruban, Gerente de Servicios de Tech Client en Advection.NET<\/p>\n<hr>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\n  &#8221; Nuestras empresas se des&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":261,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.iptp.org\/es_ES\/wp-json\/wp\/v2\/pages\/1041"}],"collection":[{"href":"https:\/\/www.iptp.org\/es_ES\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.iptp.org\/es_ES\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.iptp.org\/es_ES\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iptp.org\/es_ES\/wp-json\/wp\/v2\/comments?post=1041"}],"version-history":[{"count":217,"href":"https:\/\/www.iptp.org\/es_ES\/wp-json\/wp\/v2\/pages\/1041\/revisions"}],"predecessor-version":[{"id":36250,"href":"https:\/\/www.iptp.org\/es_ES\/wp-json\/wp\/v2\/pages\/1041\/revisions\/36250"}],"up":[{"embeddable":true,"href":"https:\/\/www.iptp.org\/es_ES\/wp-json\/wp\/v2\/pages\/261"}],"wp:attachment":[{"href":"https:\/\/www.iptp.org\/es_ES\/wp-json\/wp\/v2\/media?parent=1041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}