{"id":23955,"date":"2022-08-29T12:01:52","date_gmt":"2022-08-29T09:01:52","guid":{"rendered":"https:\/\/web-dev.iptp.net\/?page_id=23955"},"modified":"2026-04-17T10:52:55","modified_gmt":"2026-04-17T07:52:55","slug":"direct-internet-access","status":"publish","type":"page","link":"https:\/\/www.iptp.org\/es_ES\/internet-access\/direct-internet-access\/","title":{"rendered":"Acceso Directo a Internet"},"content":{"rendered":"<h2 class=\"text-normal text-primary fs-4 mt-0\">Acceso Directo a Internet de IPTP Networks: la l&iacute;nea arrendada de Internet de alta calidad y alta velocidad para operaciones comerciales.<\/h2><p><!-- \n\n<div class=\"d-flex rounded p-2 mb-4\" style=\"background:url('\/wp-content\/uploads\/ill1.png') no-repeat left\/cover;\">\n   \n\n<div class=\"ms-auto text-end p-4 pb-0\">\n      \n\n<div><img decoding=\"async\" src=\"\/wp-content\/uploads\/dia-icon.svg\" class=\"mb-4\" alt=\"dia-icon\"\/><\/div>\n\n\n      \n\n<h2 class=\"dia-title m-0 fw-bold\">DIA<\/h2>\n\n\n      \n\n<p class=\"dia-des\">Acceso Directo a Internet<\/p>\n\n\n      <button class=\"btn btn-secondary px-5 py-3 text-white js-target-div\" data-target=\"jumboIX__modal\">SOLICITAR COTIZACI&Oacute;N<\/button>\n   <\/div>\n\n\n<\/div>\n\n --><br>\nEl Acceso Directo a Internet (DIA), o l&iacute;nea alquilada de Internet, es conectividad a Internet con una IP est&aacute;tica. El DIA proporciona conectividad a nivel nacional e internacional: la opci&oacute;n ideal para cualquier empresa que desee tener presencia en l&iacute;nea o acceso a Internet. <\/p><p>A trav&eacute;s de nuestra red troncal privada global de m&aacute;s de 228 POP que cubren 64 ciudades en 37 pa&iacute;ses y nuestra diversa cartera de socios de red, podemos proporcionar acceso directo a Internet con un rendimiento excelente a un precio moderado. <\/p><p>Exp&aacute;ndete r&aacute;pidamente a todas las ubicaciones deseables y permite que tus clientes se comuniquen contigo sin inconvenientes con una red troncal privada de alta velocidad, baja latencia, altamente robusta, protegida por el servicio de mitigaci&oacute;n de DDoS, diversificada geogr&aacute;ficamente y redundante.<\/p><div class=\"bg-primary p-3 rounded is-shadow mb-5\">\n<div class=\"row g-3\">\n<div class=\"col-12 col-lg-3 text-lg-end text-center p-lg-4 p-2\">\n<div class=\"mb-lg-5 mb-4\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" width=\"70\" alt=\"transit\" data-src=\"\/wp-content\/uploads\/transit.svg\" class=\"lazy\"><\/div>\n<p class=\"text-white fs-5\">El Acceso Directo a Internet es la opci&oacute;n ideal para empresas de r&aacute;pido crecimiento que necesitan:<\/p>\n<\/div>\n<div class=\"col-12 col-lg-9\">\n<div class=\"rounded bg-white p-4 h-100\">\n<ul class=\"list-unstyled\">\n<li class=\"mb-3\">&mdash; Conexi&oacute;n a Internet confiable y r&aacute;pida compatible con puertos de 10Mb hasta 100G.<\/li>\n<li class=\"mb-3\">&mdash; Comunicaci&oacute;n fluida para aplicaciones de tiempo cr&iacute;tico como video, voz, transacciones financieras o una experiencia de juego fluida.<\/li>\n<li class=\"mb-3\">&mdash; Minimiza el efecto de posibles ataques DDoS volum&eacute;tricos.<\/li>\n<li class=\"mb-3\">&mdash; Evita la complejidad y el costo de configurar sus propios enrutadores ASN y BGP.<\/li>\n<li class=\"mb-3\">&mdash; Tranquilidad con el servicio de Internet administrado de un solo proveedor comprometido.<\/li>\n<\/ul><\/div>\n<\/div>\n<\/div>\n<\/div><h3 class=\"text-center mb-5\">BENEFICIOS DEL ACCESO DIRECTO A INTERNET DE IPTP NETWORKS<\/h3><div class=\"row row-cols-1 row-cols-lg-2 g-3 mb-5 justify-content-center\">\n<div class=\"col\">\n<div class=\"box1 box-icon h-100 p-4\">\n<div class=\"d-flex flex-nowrap mb-4\">\n<div class=\"box-icon-img\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"bestpath2\" data-src=\"\/wp-content\/uploads\/bestpath2.svg\" class=\"lazy\"><\/div>\n<h3 class=\"boxi-title my-0 text-primary fw-bold\">Disponibilidad Mundial<\/h3>\n<\/div>\n<p>Nuestra soluci&oacute;n de Acceso Directo a Internet est&aacute; disponible en las ubicaciones m&aacute;s exigentes en 37 pa&iacute;ses de Asia, &Aacute;frica, Am&eacute;rica del Norte, Am&eacute;rica del Sur, Europa y Australia.<\/p>\n<\/div>\n<\/div>\n<div class=\"col\">\n<div class=\"box1 box-icon h-100 p-4\">\n<div class=\"d-flex flex-nowrap mb-4\">\n<div class=\"box-icon-img\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"nmap\" data-src=\"\/wp-content\/uploads\/nmap.svg\" class=\"lazy\"><\/div>\n<h3 class=\"boxi-title my-0 text-primary fw-bold\">Cobertura Nacional Excepcional<\/h3>\n<\/div>\n<p>Nuestra l&iacute;nea arrendada de Internet est&aacute; bien conectada a nivel internacional y nacional. Nuestra conexi&oacute;n estable con los principales ISP locales y los intercambios de Internet del mercado garantiza el mejor rendimiento posible a nivel nacional e internacional.<\/p>\n<\/div>\n<\/div>\n<div class=\"col\">\n<div class=\"box1 box-icon h-100 p-4\">\n<div class=\"d-flex flex-nowrap mb-4\">\n<div class=\"box-icon-img\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"nmap\" data-src=\"\/wp-content\/uploads\/capacity.svg\" class=\"lazy\"><\/div>\n<h3 class=\"boxi-title my-0 text-primary fw-bold\">Velocidad Incre&iacute;ble<\/h3>\n<\/div>\n<p>Gracias a la red troncal global de baja latencia de IPTP Networks, nuestra velocidad de Internet DIA para la mayor&iacute;a de los destinos internacionales siempre superar&aacute; a los ISP nacionales que com&uacute;nmente se enfocan en el bajo costo. La variedad de enlaces a trav&eacute;s de nuestra red troncal tambi&eacute;n asegura nuestra posici&oacute;n de liderazgo mundial.<\/p>\n<\/div>\n<\/div>\n<div class=\"col\">\n<div class=\"box1 box-icon h-100 p-4\">\n<div class=\"d-flex flex-nowrap mb-4\">\n<div class=\"box-icon-img\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"nmap\" data-src=\"\/wp-content\/uploads\/oreliab.svg\" class=\"lazy\"><\/div>\n<h3 class=\"boxi-title my-0 text-primary fw-bold\">Fiabilidad<\/h3>\n<\/div>\n<p>Nuestra red implementa cientos de puntos de inspecci&oacute;n de tr&aacute;fico para garantizar la supresi&oacute;n del 90 % de todos los ataques volum&eacute;tricos com&uacute;nmente conocidos. Adem&aacute;s, los enrutadores de 2 a 3 n&uacute;cleos por mercado agregan una gran redundancia para brindarles a los clientes una conectividad confiable y sin interrupciones.<\/p>\n<\/div>\n<\/div>\n<div class=\"col\">\n<div class=\"box1 box-icon h-100 p-4\">\n<div class=\"d-flex flex-nowrap mb-4\">\n<div class=\"box-icon-img\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"nmap\" data-src=\"\/wp-content\/uploads\/shippingico.svg\" class=\"lazy\"><\/div>\n<h3 class=\"boxi-title my-0 text-primary fw-bold\">Entrega R&aacute;pida<\/h3>\n<\/div>\n<p>Configuraci&oacute;n r&aacute;pida en 228 centros de datos de todo el mundo con opciones de &uacute;ltima milla disponibles. Sin requisitos de ASN (N&uacute;mero de Sistema Aut&oacute;nomo). Accede inmediatamente a Internet sin ning&uacute;n proceso complicado.<\/p>\n<\/div>\n<\/div>\n<div class=\"col\">\n<div class=\"box1 box-icon h-100 p-4\">\n<div class=\"d-flex flex-nowrap mb-4\">\n<div class=\"box-icon-img\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"nmap\" data-src=\"\/wp-content\/uploads\/purchasingico.svg\" class=\"lazy\"><\/div>\n<h3 class=\"boxi-title my-0 text-primary fw-bold\">Rentable<\/h3>\n<\/div>\n<p>El Acceso Directo a Internet cuenta con el mejor rendimiento posible al precio m&aacute;s bajo entre todas las soluciones de conectividad.<\/p>\n<\/div>\n<\/div>\n<div class=\"col\">\n<div class=\"box1 box-icon h-100 p-4\">\n<div class=\"d-flex flex-nowrap mb-4\">\n<div class=\"box-icon-img\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"nmap\" data-src=\"\/wp-content\/uploads\/uptime.svg\" class=\"lazy\"><\/div>\n<h3 class=\"boxi-title my-0 text-primary fw-bold\">Alta Disponibilidad: SLA de hasta 99,999 %<\/h3>\n<\/div>\n<p>La l&iacute;nea arrendada de Internet est&aacute; respaldada por nuestra red troncal privada garantizada por SLA con m&uacute;ltiples opciones de resiliencia (protecci&oacute;n de enlaces y nodos), lo que le brinda una confiabilidad extrema de acuerdo con los est&aacute;ndares de la industria financiera y bancaria.<\/p>\n<\/div>\n<\/div>\n<div class=\"col\">\n<div class=\"box1 box-icon h-100 p-4\">\n<div class=\"d-flex flex-nowrap mb-4\">\n<div class=\"box-icon-img\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"nmap\" data-src=\"\/wp-content\/uploads\/customersico.svg\" class=\"lazy\"><\/div>\n<h3 class=\"boxi-title my-0 text-primary fw-bold\">Soporte 24\/7\/365<\/h3>\n<\/div>\n<ul>\n<li>Supervisi&oacute;n proactiva de la red.<\/li>\n<li>Servicio de soporte t&eacute;cnico calificado.<\/li>\n<li>Servicio de soporte de mantenimiento.<\/li>\n<\/ul><\/div>\n<\/div>\n<\/div><h2 class=\"text-center mb-5 text-secondary\">UBICACI&Oacute;N DEL SERVICIO DE L&Iacute;NEA ARRENDADA DE INTERNET<\/h2><p class=\"mb-4\">IPTP Networks proporciona el servicio de acceso directo a Internet en todos los pa&iacute;ses seleccionados en azul en el mapa global.<\/p><link rel=\"stylesheet\" target=\"_blank\" href=\"\/wp-content\/themes\/iptp-theme\/lib\/leaflet\/leaflet.css\"><script src=\"\/wp-content\/themes\/iptp-theme\/lib\/leaflet\/leaflet.js\"><\/script><script type=\"text\/javascript\" src=\"\/wp-content\/themes\/iptp-theme\/lib\/jquery-ui.min.js\"><\/script><script type=\"text\/javascript\" src=\"\/wp-content\/themes\/iptp-theme\/lib\/leaflet\/imgViewer2.js\"><\/script><div class=\"wrap-img\">\r\n    <button class=\"btn-modal-toggle-js btn-toggle-modal-css btn btn-primary\"><img class=\"disabled-lazy\" src=\"\/wp-content\/themes\/iptp-theme\/images\/searchplus.svg\" alt=\"zoom\" style=\"width:18px;height:18px;background: none;\"><\/button><img class=\"img-zoom disabled-lazy\" src=\"\/map\/\" alt=\"pop-map\"><\/div><div class=\"pos-full-width div-toggle-js\" align=\"center\">\r\n    <button class=\"btn-modal-toggle-js btn-toggle-modal-css btn btn-primary\"><img class=\"disabled-lazy\" src=\"\/wp-content\/themes\/iptp-theme\/images\/close_write.svg\" alt=\"close\" style=\"width:14px;height:14px;\"><\/button> <img class=\"img-zoom-large disabled-lazy\" src=\"\/map\/\" alt=\"pop-map\"><\/div><p class=\"mt-4\">&iquest;Quieres llegar a empresas de una regi&oacute;n completamente diferente sin comprometer la latencia y el ancho de banda?<\/p><p> IPTP Networks tambi&eacute;n ofrece <a href=\"https:\/\/www.iptp.org\/es_ES\/internet-access\/remote-dia\/\">Remote DIA<\/a>, un servicio DIA dentro de sitios remotos a trav&eacute;s de redes troncales L2 EoMPLS protegidas.<\/p><div class=\"text-center my-5\">\n   \t\r\n\r\n\t\r\n\t<div>\r\n\t\t<button type=\"button\" class=\"btn btn-primary btn__jumboix btn-lg js-target-div mt-2 js-fixed-button-open-request-form btn-second btn-post-larger\" data-target=\"jumboIX__modal\">\r\n\t\t\tSOLICITAR COTIZACI&Oacute;N\t\t<\/button>\r\n\t<\/div>\r\n\t\r\n\t<script type=\"text\/javascript\">\r\n\t\tjQuery(function($){\r\n\r\n\t\t\t $(document).on('click', '#jumboIX__modal.active', function(e){\r\n\t\t        e.preventDefault();\r\n\r\n\t\t        $(this).find('.js-x-close').trigger('click');   \r\n\t\t    });\r\n\r\n\t\t    $(document).on('click', '#jumboIX__modal.active *', function(e){\r\n\t\t        e.stopPropagation();\r\n\r\n\t\t    });\r\n\r\n\t\t})\r\n\t<\/script>\r\n\r\n\t<div id=\"jumboIX__modal\" class=\"popup-jumboIX-modal-s1 wrap-jumboix wrap-jumboix__2 v-modal\">\r\n\t\t<div class=\"modal__inner\">\r\n\t\t\t<button class=\"x-close js-x-close\">x<\/button>\r\n\r\n\t\t\t<h2 class=\"jumbolix-heading \">\r\n\t\t\t\tAcceso Directo a Internet\t\t\t<\/h2>\r\n\r\n\t\t\t\r\n\t\t\t<form method=\"post\" class=\"js-form-ajax-request_form css-form-mod-v2 js_form_get_token\">\r\n\t\t\t\t   <input type=\"hidden\" name=\"_wp_http_referer\" value=\"https:\/\/www.iptp.org\/es_ES\/wp-json\/wp\/v2\/pages\/23955\" class=\"no-check\">\r\n   <input type=\"hidden\" name=\"_current_title\" value=\"IPTP Networks\" class=\"no-check\">\r\n   <input type=\"hidden\" name=\"security\" value=\"6f8533b9eb\">\r\n   <input type=\"hidden\" name=\"form_time\" value=\"1778711188\">\r\n   <input type=\"text\" name=\"website\" style=\"display:none\" class=\"no-check\">\r\n   <input type=\"hidden\" name=\"js_check\" class=\"no-check\" value=\"\">\r\n   \r\n\r\n\t\t\t\t\t\t\t\t\t<input type=\"hidden\" name=\"service\" value=\"Acceso Directo a Internet\">\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"row\">\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-6 line-group\">\r\n\t\t\t\t\t\t<input type=\"text\" name=\"your_name\" class=\"form-control form-control--border-bottom\" placeholder=\"Your name *\">\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-6 line-group\">\r\n\t\t\t\t\t\t<input type=\"text\" name=\"email\" class=\"form-control form-control--border-bottom\" placeholder=\"E-mail *\">\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"clearfix\"><\/div>\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-6 line-group\">\r\n\t\t\t\t\t\t<input type=\"text\" name=\"organisation\" class=\"form-control form-control--border-bottom\" placeholder=\"Organisation *\">\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-6 line-group\">\r\n\t\t\t\t\t\t<div class=\"wrap-intl-tel-input\">\r\n\t\t\t\t\t\t\t<input type=\"text\" name=\"asnumber\" class=\"form-control form-control--border-bottom intl-tel-input no-check\" placeholder=\"Phone Number\">\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\r\n\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"clearfix\"><\/div>\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-12 line-group\">\r\n\t\t\t\t\t\t<div class=\"w-100\">\r\n\t\t\t\t\t\t\t<label style=\"font-weight: bold\" for=\"ms\">Describe your request<\/label>\r\n\t\t\t\t\t\t\t<textarea name=\"message\" id=\"ms\" cols=\"30\" rows=\"6\" class=\"form-control form-control--border-bottom\" placeholder=\"Quick overview *\"><\/textarea>\r\n\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-12 line-group\">\r\n\t\t\t\t\t\t* required fields\t\t\t\t\t<\/div>\r\n\r\n\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-12 text-center\">\r\n\t\t\t\t\t<!-- \t<div class=\"line-group captcha_md\">\r\n\t\t\t\t\t\t\t<div id=\"captchas\" class=\"captcha__label\" data-qid=\"captcha_6a04fa940ca64\"><\/div>\r\n\t\t\t\t\t\t\t<span class=\"fa fa-refresh catpcha_refreshs catpcha_refresh_mod\"><\/span>\r\n\t\t\t\t\t\t\t<input id=\"cpatchaJumboIX\" type=\"text\" name=\"captcha\" class=\"line-group__input--213 captcha__input--custom\" placeholder=\"Captcha code\" \/>\r\n\t\t\t\t\t\t<\/div> -->\r\n\t\t\t\t\t\t<div class=\"line-groups\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"hidden-sm hidden-xs\"><\/div>\r\n\t\t\t\t\t\t\t<button class=\"btn btn__jumboix\">\r\n\t\t\t\t\t\t\t\tSOLICITAR COTIZACI&Oacute;N\t\t\t\t\t\t\t<\/button>\r\n\t\t\t\t\t\t<\/div>\r\n\r\n\r\n\r\n\t\t\t\t\t\t<div class=\"jumboIX_completed js-jumboIX_completed--success \">\r\n\t\t\t\t\t\t\tGracias por tu solicitud\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div class=\"jumboIX_completed jumboIX_completed--error\"><\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/form>\r\n\t\t<\/div>\r\n\t<\/div>\r\n\t<div class=\"div-overlay\"><\/div>\r\n\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&#8230;<\/p>\n","protected":false},"author":14,"featured_media":0,"parent":388,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.iptp.org\/es_ES\/wp-json\/wp\/v2\/pages\/23955"}],"collection":[{"href":"https:\/\/www.iptp.org\/es_ES\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.iptp.org\/es_ES\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.iptp.org\/es_ES\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iptp.org\/es_ES\/wp-json\/wp\/v2\/comments?post=23955"}],"version-history":[{"count":76,"href":"https:\/\/www.iptp.org\/es_ES\/wp-json\/wp\/v2\/pages\/23955\/revisions"}],"predecessor-version":[{"id":40349,"href":"https:\/\/www.iptp.org\/es_ES\/wp-json\/wp\/v2\/pages\/23955\/revisions\/40349"}],"up":[{"embeddable":true,"href":"https:\/\/www.iptp.org\/es_ES\/wp-json\/wp\/v2\/pages\/388"}],"wp:attachment":[{"href":"https:\/\/www.iptp.org\/es_ES\/wp-json\/wp\/v2\/media?parent=23955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}