{"id":11025,"date":"2019-07-24T15:51:47","date_gmt":"2019-07-24T12:51:47","guid":{"rendered":"https:\/\/web-dev.iptp.com\/?page_id=11025"},"modified":"2026-04-17T06:37:16","modified_gmt":"2026-04-17T03:37:16","slug":"best-path","status":"publish","type":"page","link":"https:\/\/www.iptp.org\/pt_PT\/iptp-tools\/best-path\/","title":{"rendered":"Melhor caminho (Best Path)"},"content":{"rendered":"<div class=\"fs-14 mt-5\">\n<p>Nota: as rotas ultracurtas n&atilde;o fazem parte da rede p&uacute;blica, voc&ecirc; pode verificar informa&ccedil;&otilde;es reais com o departamento de vendas. (Envie a solicita&ccedil;&atilde;o para <a><span class=\"sp-user\">sales<\/span><span class=\"sp-domain\">iptp.net<\/span><\/a>).<\/p>\n<p class=\"text-secondary\">O c&aacute;lculo &eacute; apenas para refer&ecirc;ncia. As Lat&ecirc;ncias\/MTU est&atilde;o sujeitas a verifica&ccedil;&atilde;o.<\/p>\n<div class=\"row box-shadow mb-4\">\n<div class=\"col-12 col-lg-8 p-3 p-lg-4\">\n<h4 class=\"mb-3\">CONTATO<\/h4>\n<p>Para quaisquer d&uacute;vidas e perguntas, sinta-se &agrave; vontade para entrar em contato com nossa equipe em <a><span class=\"sp-user\">sales<\/span><span class=\"sp-domain\">iptp.net<\/span><\/a> ou pressione o bot&atilde;o &laquo;<a class=\"text-primary c-cursor js-target-div\" data-target=\"jumboIX__modal\">Solicitar um or&ccedil;amento<\/a>&raquo;.<\/p>\n<p class=\"mb-0\">Se voc&ecirc; tiver algum problema com este site, informe-o para <a><span class=\"sp-user\">cs<\/span><span class=\"sp-domain\">iptp.net<\/span><\/a> ou use o bot&atilde;o &laquo;<a href=\"javascript:popupchat()\">Live Assistant<\/a>&raquo; no canto inferior direito da p&aacute;gina da web.<\/p>\n<\/div>\n<div class=\"col-12 col-lg-4 contact_bg py-5\">\n         <a href=\"https:\/\/www.iptp.org\/pt_PT\/best-path-app\/\" class=\"text-uppercase btn btn-primary px-5 rounded have-shadow text-center\" target=\"_blank\" rel=\"noopener\">VOC&Ecirc; PRECISA DE UMA<br>BEST PATH PERSONALIZADA?<\/a>\n      <\/div>\n<\/div>\n<section>\n<div class=\"row\">\n<div class=\"col-12 col-lg-4 bp-sidebar p-3 p-lg-4\">\n<div class=\"nav bp-nav flex-column nav-pills me-3\" id=\"v-pills-tab\" role=\"tablist\" aria-orientation=\"vertical\">\n               <button class=\"nav-link text-start active\" id=\"bp-tab-sec1\" data-bs-toggle=\"pill\" data-bs-target=\"#bp-content-sec1\" type=\"button\" role=\"tab\" aria-controls=\"v-pills-home\" aria-selected=\"true\">DEFINI&Ccedil;&Atilde;O DA BEST PATH<\/button><br>\n               <button class=\"nav-link text-start js-bp-tab-sec2-target\" id=\"bp-tab-sec2\" data-bs-toggle=\"pill\" data-bs-target=\"#bp-content-sec2\" type=\"button\" role=\"tab\" aria-controls=\"v-pills-profile\" aria-selected=\"false\">COMO USAR?<\/button><br>\n               <button class=\"nav-link text-start js-bp-tab-sec3-target\" id=\"bp-tab-sec3\" data-bs-toggle=\"pill\" data-bs-target=\"#bp-content-sec3\" type=\"button\" role=\"tab\" aria-controls=\"v-pills-disabled\" aria-selected=\"false\">ENTENDA OS RESULTADOS<\/button><br>\n               <button class=\"nav-link text-start js-bp-tab-sec4-target\" id=\"bp-tab-sec4\" data-bs-toggle=\"pill\" data-bs-target=\"#bp-content-sec4\" type=\"button\" role=\"tab\" aria-controls=\"v-pills-messages\" aria-selected=\"false\">CAIXAS DE APOIO<\/button><br>\n               <button class=\"nav-link text-start js-bp-tab-sec5-target\" id=\"bp-tab-sec5\" data-bs-toggle=\"pill\" data-bs-target=\"#bp-content-sec5\" type=\"button\" role=\"tab\" aria-controls=\"v-pills-settings\" aria-selected=\"false\">O MAPA<\/button>\n            <\/div>\n<\/div>\n<div class=\"col-12 col-lg-8 p-3 p-lg-4 bp-content box-shadow\">\n<div class=\"tab-content\" id=\"v-pills-tabContent\">\n<div class=\"tab-pane fade show active\" id=\"bp-content-sec1\" role=\"tabpanel\" aria-labelledby=\"bp-tab-sec1\" tabindex=\"0\">\n<p>Best Path &eacute; o nome da nossa ferramenta especial, que usamos para ilustrar as lat&ecirc;ncias corretas entre os n&oacute;s do backbone IPTP Networks.<\/p>\n<h2>POR QUE BEST PATH &Eacute; &Uacute;TIL?<\/h2>\n<p>Nossa pr&oacute;pria ferramenta Best Path sempre oferece uma melhor visualiza&ccedil;&atilde;o de rotas e lat&ecirc;ncias, transformando o mapa global da rede de distribui&ccedil;&atilde;o IPTP em dados detalhados.<\/p>\n<p>Gra&ccedil;as a isso, os usu&aacute;rios podem ter uma imagem mais compreens&iacute;vel de cada conectividade, incluindo as rotas protegidas, a disponibilidade das rotas e outros requisitos particulares. A partir dessas informa&ccedil;&otilde;es, os clientes podem projetar livremente suas rotas ideais sem esfor&ccedil;o.<\/p>\n<p class=\"text-md-end text-center\"><button class=\"btn btn-primary btn-lg rounded text-uppercase btn-has-icon js-bp-tab-sec1\">COMO USAR?<\/button><\/p>\n<\/div>\n<div class=\"tab-pane fade\" id=\"bp-content-sec2\" role=\"tabpanel\" aria-labelledby=\"bp-tab-sec2\" tabindex=\"0\">\n<p>Para iniciar a pesquisa:<\/p>\n<p>1) Escolha os n&oacute;s desejados no menu suspenso<\/p>\n<p class=\"text-center\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" class=\"img-fluid lazy\" alt=\"\" data-src=\"\/wp-content\/uploads\/select-from-location.png\"><\/p>\n<p>2) Escolha caixas adequadas. Existem 4 op&ccedil;&otilde;es de suporte para mostrar um resultado mais diversificado:<\/p>\n<div class=\"row g-4 row-cols-sm-2 row-cols-1 mb-4\">\n<div class=\"col\">\n<div class=\"form-check btn p-3 px-md-5 btn-primary w-100 rounded ps-5 text-start\">\n                           <input class=\"form-check-input\" type=\"checkbox\" value=\"\" id=\"linkcheck\"><br>\n                           <label class=\"form-check-label\" for=\"linkcheck\"><br>\n                           Link protection<br>\n                           <\/label>\n                        <\/div>\n<\/div>\n<div class=\"col\">\n<div class=\"form-check btn p-3 px-md-5 btn-primary w-100 rounded ps-5 text-start\">\n                           <input class=\"form-check-input\" type=\"checkbox\" value=\"\" id=\"actualcheck\" checked><br>\n                           <label class=\"form-check-label\" for=\"actualcheck\"><br>\n                           Actual information only<br>\n                           <\/label>\n                        <\/div>\n<\/div>\n<div class=\"col\">\n<div class=\"form-check btn p-3 px-md-5 btn-primary w-100 rounded ps-5 text-start\">\n                           <input class=\"form-check-input\" type=\"checkbox\" value=\"\" id=\"nodecheck\" checked><br>\n                           <label class=\"form-check-label\" for=\"nodecheck\"><br>\n                           Node Protection<br>\n                           <\/label>\n                        <\/div>\n<\/div>\n<div class=\"col\">\n<div class=\"form-check btn p-3 px-md-5 btn-primary w-100 rounded ps-5 text-start\">\n                           <input class=\"form-check-input\" type=\"checkbox\" value=\"\" id=\"avoidcheck\" checked><br>\n                           <label class=\"form-check-label\" for=\"avoidcheck\"><br>\n                           Avoid node in USA<br>\n                           <\/label>\n                        <\/div>\n<\/div>\n<\/div>\n<p>3) Clique no bot&atilde;o &laquo;Calcular caminho&raquo; para finalizar a pesquisa e ver os resultados.<\/p>\n<div class=\"text-center mb-5\">\n<div class=\"bg-primary py-3 px-4 rounded d-inline-block\"><button class=\"bp-button\">Calculate Path<\/button><\/div>\n<\/div>\n<p class=\"text-md-end text-center\"><button class=\"btn btn-primary rounded btn-lg text-uppercase btn-has-icon js-bp-tab-sec2\">INTERPRETAR LOS RESULTADOS<\/button><\/p>\n<\/div>\n<div class=\"tab-pane fade\" id=\"bp-content-sec3\" role=\"tabpanel\" aria-labelledby=\"bp-tab-sec3\" tabindex=\"0\">\n<p>O resultado tem 2 partes: o n&uacute;mero e o mapa. Isso aparece como o exemplo abaixo:<\/p>\n<p>A parte do n&uacute;mero mostra todos os detalhes sobre a rota solicitada:<\/p>\n<p class=\"text-center\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" class=\"img-fluid lazy\" alt=\"\" data-src=\"\/wp-content\/uploads\/bp-overview.png\"><\/p>\n<p>No qual,<\/p>\n<p class=\"mb-0\">A) &ldquo;Latency: 49 ms&rdquo; &eacute; a lat&ecirc;ncia de toda a rota, com 98,00 ms &eacute; o RTD,<\/p>\n<p class=\"mb-0\">B) A unidade de transfer&ecirc;ncia m&aacute;xima (MTU) geralmente em torno de 9000, <\/p>\n<p class=\"mb-0\">C) &ldquo;SY5 Equinix, Sydney, AU&rdquo;, &ldquo;GNC Guam&rdquo;, e &ldquo;TY2 Equinix, Tokyo, JP&rdquo; s&atilde;o os n&oacute;s, <\/p>\n<p class=\"mb-0\">&ndash; &ldquo;JGA-S&rdquo; e &ldquo;JGA-N&rdquo; s&atilde;o os cabos utilizados neste caminho, <\/p>\n<p>&ndash; &ldquo;35.00 ms&rdquo; e &ldquo;14.00 ms&rdquo; s&atilde;o as lat&ecirc;ncias, <\/p>\n<p class=\"mb-0\">&ndash; Linha pontilhada: segunda rota <\/p>\n<p class=\"mb-0\">&ndash; <span class=\"text-primary\">Linha azul escura<\/span>: rota real, <\/p>\n<p class=\"mb-0\">&ndash; <span class=\"text-info\">Linha azul Clara<\/span>: uma rota planejada para o pr&oacute;ximo hor&aacute;rio, <\/p>\n<p class=\"mb-0\">&ndash; <span class=\"text-secondary\">Linha laranja<\/span>: as rotas est&atilde;o dispon&iacute;veis somente quando solicitadas.<\/p>\n<p class=\"text-md-end text-center mt-5\"><button class=\"btn btn-primary rounded btn-lg text-uppercase btn-has-icon js-bp-tab-sec3\">CAIXAS DE APOIO<\/button><\/p>\n<\/div>\n<div class=\"tab-pane fade\" id=\"bp-content-sec4\" role=\"tabpanel\" aria-labelledby=\"bp-tab-sec4\" tabindex=\"0\">\n<p>Normalmente, se voc&ecirc; executar a pesquisa sem escolher nenhum requisito adicional, o resultado mostrar&aacute; apenas o <strong>Caminho Principal<\/strong> da rota solicitada. No entanto, tamb&eacute;m fornecemos muitas op&ccedil;&otilde;es, conforme mencionado na etapa 2 de &laquo;Como usar a ferramenta Best Path?&raquo;, para fornecer uma resposta mais detalhada, incluindo diversos caminhos para serem usados como backup sempre que o principal estiver inativo.<\/p>\n<p>Em seguida, vamos dar uma olhada no significado de cada caixa de suporte da ferramenta <strong>Best Path<\/strong>.<\/p>\n<h3 class=\"fs-6\">A PARTE NUM&Eacute;RICA<\/h3>\n<h4 class=\"fs-6 fw-bold\">Prote&ccedil;&atilde;o de link:<\/h4>\n<p>Juntamente com o prim&aacute;rio, se voc&ecirc; tamb&eacute;m quiser ver caminhos diversos (que evitam cabos usados no prim&aacute;rio), vamos escolher &laquo;Prote&ccedil;&atilde;o de link&raquo;.<\/p>\n<p class=\"text-center\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" class=\"img-fluid lazy\" alt=\"\" data-src=\"\/wp-content\/uploads\/l.png\"><\/p>\n<h4 class=\"fs-6 fw-bold\">Prote&ccedil;&atilde;o de n&oacute;:<\/h4>\n<p>Mas se voc&ecirc; tamb&eacute;m quiser evitar o POP usado no prim&aacute;rio, escolha &laquo;Prote&ccedil;&atilde;o de n&oacute;&raquo;.<\/p>\n<p class=\"text-center\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" class=\"img-fluid lazy\" alt=\"\" data-src=\"\/wp-content\/uploads\/node.png\"><\/p>\n<h4 class=\"fs-6 fw-bold\">Actual Information Only:<\/h4>\n<p>Clique na caixa &laquo;Actual Information Only&raquo; para visualizar apenas os caminhos on-net, n&atilde;o os &laquo;Dispon&iacute;veis mediante solicita&ccedil;&atilde;o&raquo;.<\/p>\n<p class=\"text-center\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" class=\"img-fluid lazy\" alt=\"\" data-src=\"\/wp-content\/uploads\/actual.png\"><\/p>\n<h4 class=\"fs-6 fw-bold\">Evitar n&oacute;s nos EUA:<\/h4>\n<p>Clique em &laquo;Evitar n&oacute;s nos EUA&raquo; para ver as rotas que n&atilde;o param nesta regi&atilde;o.<\/p>\n<p class=\"text-center\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" class=\"img-fluid lazy\" alt=\"\" data-src=\"\/wp-content\/uploads\/avoid-node.png\"><\/p>\n<p>Neste exemplo, &laquo;LA1 Coresite, Los Angeles, US&raquo; foi removido.<\/p>\n<p class=\"text-md-end text-center mt-5\"><button class=\"btn btn-primary rounded btn-lg text-uppercase btn-has-icon js-bp-tab-sec4\">O MAPA<\/button><\/p>\n<\/div>\n<div class=\"tab-pane fade\" id=\"bp-content-sec5\" role=\"tabpanel\" aria-labelledby=\"bp-tab-sec5\" tabindex=\"0\">\n<p>O caminho prim&aacute;rio &eacute; ilustrado no mapa como uma linha s&oacute;lida, enquanto o caminho diverso aparece como uma linha tracejada. Apesar da forma, a cor dessas linhas ainda tem o mesmo significado mencionado acima:<\/p>\n<p class=\"mb-0\"><span class=\"text-primary\">Linha azul escura<\/span>: rota real,<\/p>\n<p class=\"mb-0\"><span class=\"text-info\">Linha azul clara<\/span>: uma rota planejada para o pr&oacute;ximo hor&aacute;rio,<\/p>\n<p><span class=\"text-secondary\">Linha laranja<\/span>: as rotas est&atilde;o dispon&iacute;veis somente quando solicitadas.<\/p>\n<div class=\"row g-0 rounded mb-5\">\n<div class=\"col-12 col-md-5 bg-primary text-white rounded-start p-3 p-md-4\">\n<p>Por exemplo, voc&ecirc; pode ver nesta imagem: o caminho prim&aacute;rio &eacute; uma linha s&oacute;lida azul clara (Planejado), enquanto o caminho Diverso &eacute; uma linha tracejada azul escura (Real).<\/p>\n<p>Em combina&ccedil;&atilde;o com o uso desta ferramenta Best Path,<\/p>\n<p>Para ver melhor o mapa da rede IPTP, visite <a href=\"\/map\/\" class=\"text-info\" target=\"_blank\" rel=\"noopener\">Network map<\/a>.<\/p>\n<\/div>\n<div class=\"col-12 col-md-7 ps-md-0\">\n<div class=\"text-center rounded-3\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" class=\"img-fluid w-100 lazy\" alt=\"2nd-map\" data-src=\"\/wp-content\/uploads\/2nd-map.png\"><\/div>\n<\/div>\n<\/div>\n<p>Para ler mais sobre nosso backbone global e conectividades de baixa lat&ecirc;ncia, d&ecirc; uma olhada em nosso servi&ccedil;o de <a href=\"https:\/\/www.iptp.org\/pt_PT\/internet-access\/low-latency-routes\/\" target=\"_blank\" rel=\"noopener\">Rotas de Baixa Lat&ecirc;ncia<\/a>.<\/p>\n<p>Para conectar de forma transparente a sede e as filiais em todo o mundo para estabelecer um backbone forte sem diminuir o desempenho ou alterar as configura&ccedil;&otilde;es, n&atilde;o se esque&ccedil;a do nosso <a href=\"https:\/\/www.iptp.org\/pt_PT\/network\/connectivity-services\/eompls-pseudowire-service\/\" target=\"_blank\" rel=\"noopener\">Servicio EoMPLS Pseudowire<\/a>.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":276,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-bestpath-new-ver2.php","meta":[],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.iptp.org\/pt_PT\/wp-json\/wp\/v2\/pages\/11025"}],"collection":[{"href":"https:\/\/www.iptp.org\/pt_PT\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.iptp.org\/pt_PT\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.iptp.org\/pt_PT\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iptp.org\/pt_PT\/wp-json\/wp\/v2\/comments?post=11025"}],"version-history":[{"count":187,"href":"https:\/\/www.iptp.org\/pt_PT\/wp-json\/wp\/v2\/pages\/11025\/revisions"}],"predecessor-version":[{"id":39987,"href":"https:\/\/www.iptp.org\/pt_PT\/wp-json\/wp\/v2\/pages\/11025\/revisions\/39987"}],"up":[{"embeddable":true,"href":"https:\/\/www.iptp.org\/pt_PT\/wp-json\/wp\/v2\/pages\/276"}],"wp:attachment":[{"href":"https:\/\/www.iptp.org\/pt_PT\/wp-json\/wp\/v2\/media?parent=11025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}